{"id":4,"count":6,"description":"","link":"https:\/\/zoyniqit.com\/errin-demo\/home-main\/category\/gadget\/","name":"Gadget","slug":"gadget","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/zoyniqit.com\/errin-demo\/home-main\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zoyniqit.com\/errin-demo\/home-main\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/zoyniqit.com\/errin-demo\/home-main\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/zoyniqit.com\/errin-demo\/home-main\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}